{"id":1540,"date":"2025-11-17T16:53:44","date_gmt":"2025-11-17T19:53:44","guid":{"rendered":"https:\/\/brzadvogados.com.br\/?p=1540"},"modified":"2025-11-17T16:53:44","modified_gmt":"2025-11-17T19:53:44","slug":"reconhecimento-internacional-brz-advogados","status":"publish","type":"post","link":"https:\/\/brzadvogados.com.br\/en\/reconhecimento-internacional-brz-advogados\/","title":{"rendered":"(PT) Nosso s\u00f3cio Fabio Perrelli Pe\u00e7anha \u00e9 reconhecido pelo International Tax Review"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/brzadvogados.com.br\/pb\/wp-json\/wp\/v2\/posts\/1540\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pb\" title=\"PT\">PT<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in PT.<\/p>\n","protected":false},"author":3,"featured_media":1541,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Reconhecimento Internacional BRZ Advogados<\/title>\n<meta name=\"description\" content=\"Reconhecimento Internacional BRZ Advogados \u00e9 refor\u00e7ado com a nomea\u00e7\u00e3o de Fabio Perrelli Pe\u00e7anha pelo International Tax Review.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/brzadvogados.com.br\/reconhecimento-internacional-brz-advogados\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reconhecimento Internacional BRZ Advogados\" \/>\n<meta property=\"og:description\" content=\"Reconhecimento Internacional BRZ Advogados \u00e9 refor\u00e7ado com a nomea\u00e7\u00e3o de Fabio Perrelli Pe\u00e7anha pelo International Tax Review.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/brzadvogados.com.br\/reconhecimento-internacional-brz-advogados\/\" \/>\n<meta property=\"og:site_name\" content=\"BRZ Advogados\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-17T19:53:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2025\/11\/arte-site-OC-17.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"brzadvogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"brzadvogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/brzadvogados.com.br\/reconhecimento-internacional-brz-advogados\/\",\"url\":\"https:\/\/brzadvogados.com.br\/reconhecimento-internacional-brz-advogados\/\",\"name\":\"Reconhecimento Internacional BRZ Advogados\",\"isPartOf\":{\"@id\":\"https:\/\/brzadvogados.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/brzadvogados.com.br\/reconhecimento-internacional-brz-advogados\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/brzadvogados.com.br\/reconhecimento-internacional-brz-advogados\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2025\/11\/arte-site-OC-17.png\",\"datePublished\":\"2025-11-17T19:53:44+00:00\",\"author\":{\"@id\":\"https:\/\/brzadvogados.com.br\/#\/schema\/person\/11cc7dddfff8e2b74d96240f76e3111c\"},\"description\":\"Reconhecimento Internacional BRZ Advogados \u00e9 refor\u00e7ado com a nomea\u00e7\u00e3o de Fabio Perrelli Pe\u00e7anha pelo International Tax Review.\",\"breadcrumb\":{\"@id\":\"https:\/\/brzadvogados.com.br\/reconhecimento-internacional-brz-advogados\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/brzadvogados.com.br\/reconhecimento-internacional-brz-advogados\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/brzadvogados.com.br\/reconhecimento-internacional-brz-advogados\/#primaryimage\",\"url\":\"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2025\/11\/arte-site-OC-17.png\",\"contentUrl\":\"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2025\/11\/arte-site-OC-17.png\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/brzadvogados.com.br\/reconhecimento-internacional-brz-advogados\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/brzadvogados.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nosso s\u00f3cio Fabio Perrelli Pe\u00e7anha \u00e9 reconhecido pelo International Tax Review\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/brzadvogados.com.br\/#website\",\"url\":\"https:\/\/brzadvogados.com.br\/\",\"name\":\"BRZ Advogados\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/brzadvogados.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/brzadvogados.com.br\/#\/schema\/person\/11cc7dddfff8e2b74d96240f76e3111c\",\"name\":\"brzadvogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/brzadvogados.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7b9849547b5ff36a1f86aee5435f8087?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7b9849547b5ff36a1f86aee5435f8087?s=96&d=mm&r=g\",\"caption\":\"brzadvogados\"},\"url\":\"https:\/\/brzadvogados.com.br\/en\/author\/brzadvogados\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reconhecimento Internacional BRZ Advogados","description":"Reconhecimento Internacional BRZ Advogados \u00e9 refor\u00e7ado com a nomea\u00e7\u00e3o de Fabio Perrelli Pe\u00e7anha pelo International Tax Review.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/brzadvogados.com.br\/reconhecimento-internacional-brz-advogados\/","og_locale":"en_US","og_type":"article","og_title":"Reconhecimento Internacional BRZ Advogados","og_description":"Reconhecimento Internacional BRZ Advogados \u00e9 refor\u00e7ado com a nomea\u00e7\u00e3o de Fabio Perrelli Pe\u00e7anha pelo International Tax Review.","og_url":"https:\/\/brzadvogados.com.br\/reconhecimento-internacional-brz-advogados\/","og_site_name":"BRZ Advogados","article_published_time":"2025-11-17T19:53:44+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2025\/11\/arte-site-OC-17.png","type":"image\/png"}],"author":"brzadvogados","twitter_card":"summary_large_image","twitter_misc":{"Written by":"brzadvogados","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/brzadvogados.com.br\/reconhecimento-internacional-brz-advogados\/","url":"https:\/\/brzadvogados.com.br\/reconhecimento-internacional-brz-advogados\/","name":"Reconhecimento Internacional BRZ Advogados","isPartOf":{"@id":"https:\/\/brzadvogados.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/brzadvogados.com.br\/reconhecimento-internacional-brz-advogados\/#primaryimage"},"image":{"@id":"https:\/\/brzadvogados.com.br\/reconhecimento-internacional-brz-advogados\/#primaryimage"},"thumbnailUrl":"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2025\/11\/arte-site-OC-17.png","datePublished":"2025-11-17T19:53:44+00:00","author":{"@id":"https:\/\/brzadvogados.com.br\/#\/schema\/person\/11cc7dddfff8e2b74d96240f76e3111c"},"description":"Reconhecimento Internacional BRZ Advogados \u00e9 refor\u00e7ado com a nomea\u00e7\u00e3o de Fabio Perrelli Pe\u00e7anha pelo International Tax Review.","breadcrumb":{"@id":"https:\/\/brzadvogados.com.br\/reconhecimento-internacional-brz-advogados\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/brzadvogados.com.br\/reconhecimento-internacional-brz-advogados\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/brzadvogados.com.br\/reconhecimento-internacional-brz-advogados\/#primaryimage","url":"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2025\/11\/arte-site-OC-17.png","contentUrl":"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2025\/11\/arte-site-OC-17.png","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/brzadvogados.com.br\/reconhecimento-internacional-brz-advogados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/brzadvogados.com.br\/"},{"@type":"ListItem","position":2,"name":"Nosso s\u00f3cio Fabio Perrelli Pe\u00e7anha \u00e9 reconhecido pelo International Tax Review"}]},{"@type":"WebSite","@id":"https:\/\/brzadvogados.com.br\/#website","url":"https:\/\/brzadvogados.com.br\/","name":"BRZ Advogados","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/brzadvogados.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/brzadvogados.com.br\/#\/schema\/person\/11cc7dddfff8e2b74d96240f76e3111c","name":"brzadvogados","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/brzadvogados.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7b9849547b5ff36a1f86aee5435f8087?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b9849547b5ff36a1f86aee5435f8087?s=96&d=mm&r=g","caption":"brzadvogados"},"url":"https:\/\/brzadvogados.com.br\/en\/author\/brzadvogados\/"}]}},"_links":{"self":[{"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/posts\/1540"}],"collection":[{"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/comments?post=1540"}],"version-history":[{"count":0,"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/posts\/1540\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/media\/1541"}],"wp:attachment":[{"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/media?parent=1540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/categories?post=1540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/tags?post=1540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}