{"id":1704,"date":"2026-03-19T09:25:03","date_gmt":"2026-03-19T12:25:03","guid":{"rendered":"https:\/\/brzadvogados.com.br\/?p=1704"},"modified":"2026-03-19T09:25:03","modified_gmt":"2026-03-19T12:25:03","slug":"cmed-precos-medicamentos-judiciais","status":"publish","type":"post","link":"https:\/\/brzadvogados.com.br\/en\/cmed-precos-medicamentos-judiciais\/","title":{"rendered":"(PT) CMED prop\u00f5e regras para pre\u00e7os em compras judiciais de medicamentos"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/brzadvogados.com.br\/pb\/wp-json\/wp\/v2\/posts\/1704\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pb\" title=\"PT\">PT<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in PT.<\/p>\n","protected":false},"author":3,"featured_media":1705,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1704","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CMED pre\u00e7os medicamentos judiciais<\/title>\n<meta name=\"description\" content=\"CMED prop\u00f5e regras para pre\u00e7os em compras judiciais de medicamentos e levanta debates sobre limites regulat\u00f3rios no setor farmac\u00eautico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/brzadvogados.com.br\/cmed-precos-medicamentos-judiciais\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CMED pre\u00e7os medicamentos judiciais\" \/>\n<meta property=\"og:description\" content=\"CMED prop\u00f5e regras para pre\u00e7os em compras judiciais de medicamentos e levanta debates sobre limites regulat\u00f3rios no setor farmac\u00eautico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/brzadvogados.com.br\/cmed-precos-medicamentos-judiciais\/\" \/>\n<meta property=\"og:site_name\" content=\"BRZ Advogados\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-19T12:25:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2026\/03\/arte-site-OC-2026-03-19T092308.841-1024x683.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"brzadvogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"brzadvogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/brzadvogados.com.br\/cmed-precos-medicamentos-judiciais\/\",\"url\":\"https:\/\/brzadvogados.com.br\/cmed-precos-medicamentos-judiciais\/\",\"name\":\"CMED pre\u00e7os medicamentos judiciais\",\"isPartOf\":{\"@id\":\"https:\/\/brzadvogados.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/brzadvogados.com.br\/cmed-precos-medicamentos-judiciais\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/brzadvogados.com.br\/cmed-precos-medicamentos-judiciais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2026\/03\/arte-site-OC-2026-03-19T092308.841.png\",\"datePublished\":\"2026-03-19T12:25:03+00:00\",\"author\":{\"@id\":\"https:\/\/brzadvogados.com.br\/#\/schema\/person\/11cc7dddfff8e2b74d96240f76e3111c\"},\"description\":\"CMED prop\u00f5e regras para pre\u00e7os em compras judiciais de medicamentos e levanta debates sobre limites regulat\u00f3rios no setor farmac\u00eautico.\",\"breadcrumb\":{\"@id\":\"https:\/\/brzadvogados.com.br\/cmed-precos-medicamentos-judiciais\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/brzadvogados.com.br\/cmed-precos-medicamentos-judiciais\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/brzadvogados.com.br\/cmed-precos-medicamentos-judiciais\/#primaryimage\",\"url\":\"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2026\/03\/arte-site-OC-2026-03-19T092308.841.png\",\"contentUrl\":\"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2026\/03\/arte-site-OC-2026-03-19T092308.841.png\",\"width\":2560,\"height\":1707,\"caption\":\"CMED pre\u00e7os medicamentos judiciais\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/brzadvogados.com.br\/cmed-precos-medicamentos-judiciais\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/brzadvogados.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CMED prop\u00f5e regras para pre\u00e7os em compras judiciais de medicamentos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/brzadvogados.com.br\/#website\",\"url\":\"https:\/\/brzadvogados.com.br\/\",\"name\":\"BRZ Advogados\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/brzadvogados.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/brzadvogados.com.br\/#\/schema\/person\/11cc7dddfff8e2b74d96240f76e3111c\",\"name\":\"brzadvogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/brzadvogados.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7b9849547b5ff36a1f86aee5435f8087?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7b9849547b5ff36a1f86aee5435f8087?s=96&d=mm&r=g\",\"caption\":\"brzadvogados\"},\"url\":\"https:\/\/brzadvogados.com.br\/en\/author\/brzadvogados\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CMED pre\u00e7os medicamentos judiciais","description":"CMED prop\u00f5e regras para pre\u00e7os em compras judiciais de medicamentos e levanta debates sobre limites regulat\u00f3rios no setor farmac\u00eautico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/brzadvogados.com.br\/cmed-precos-medicamentos-judiciais\/","og_locale":"en_US","og_type":"article","og_title":"CMED pre\u00e7os medicamentos judiciais","og_description":"CMED prop\u00f5e regras para pre\u00e7os em compras judiciais de medicamentos e levanta debates sobre limites regulat\u00f3rios no setor farmac\u00eautico.","og_url":"https:\/\/brzadvogados.com.br\/cmed-precos-medicamentos-judiciais\/","og_site_name":"BRZ Advogados","article_published_time":"2026-03-19T12:25:03+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2026\/03\/arte-site-OC-2026-03-19T092308.841-1024x683.png","type":"image\/png"}],"author":"brzadvogados","twitter_card":"summary_large_image","twitter_misc":{"Written by":"brzadvogados","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/brzadvogados.com.br\/cmed-precos-medicamentos-judiciais\/","url":"https:\/\/brzadvogados.com.br\/cmed-precos-medicamentos-judiciais\/","name":"CMED pre\u00e7os medicamentos judiciais","isPartOf":{"@id":"https:\/\/brzadvogados.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/brzadvogados.com.br\/cmed-precos-medicamentos-judiciais\/#primaryimage"},"image":{"@id":"https:\/\/brzadvogados.com.br\/cmed-precos-medicamentos-judiciais\/#primaryimage"},"thumbnailUrl":"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2026\/03\/arte-site-OC-2026-03-19T092308.841.png","datePublished":"2026-03-19T12:25:03+00:00","author":{"@id":"https:\/\/brzadvogados.com.br\/#\/schema\/person\/11cc7dddfff8e2b74d96240f76e3111c"},"description":"CMED prop\u00f5e regras para pre\u00e7os em compras judiciais de medicamentos e levanta debates sobre limites regulat\u00f3rios no setor farmac\u00eautico.","breadcrumb":{"@id":"https:\/\/brzadvogados.com.br\/cmed-precos-medicamentos-judiciais\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/brzadvogados.com.br\/cmed-precos-medicamentos-judiciais\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/brzadvogados.com.br\/cmed-precos-medicamentos-judiciais\/#primaryimage","url":"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2026\/03\/arte-site-OC-2026-03-19T092308.841.png","contentUrl":"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2026\/03\/arte-site-OC-2026-03-19T092308.841.png","width":2560,"height":1707,"caption":"CMED pre\u00e7os medicamentos judiciais"},{"@type":"BreadcrumbList","@id":"https:\/\/brzadvogados.com.br\/cmed-precos-medicamentos-judiciais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/brzadvogados.com.br\/"},{"@type":"ListItem","position":2,"name":"CMED prop\u00f5e regras para pre\u00e7os em compras judiciais de medicamentos"}]},{"@type":"WebSite","@id":"https:\/\/brzadvogados.com.br\/#website","url":"https:\/\/brzadvogados.com.br\/","name":"BRZ Advogados","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/brzadvogados.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/brzadvogados.com.br\/#\/schema\/person\/11cc7dddfff8e2b74d96240f76e3111c","name":"brzadvogados","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/brzadvogados.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7b9849547b5ff36a1f86aee5435f8087?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b9849547b5ff36a1f86aee5435f8087?s=96&d=mm&r=g","caption":"brzadvogados"},"url":"https:\/\/brzadvogados.com.br\/en\/author\/brzadvogados\/"}]}},"_links":{"self":[{"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/posts\/1704"}],"collection":[{"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/comments?post=1704"}],"version-history":[{"count":0,"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/posts\/1704\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/media\/1705"}],"wp:attachment":[{"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/media?parent=1704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/categories?post=1704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/tags?post=1704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}