{"id":472,"date":"2024-02-29T09:51:52","date_gmt":"2024-02-29T12:51:52","guid":{"rendered":"https:\/\/brzadvogados.com.br\/?p=472"},"modified":"2024-07-29T10:53:53","modified_gmt":"2024-07-29T13:53:53","slug":"aquisicoes-diretas-de-medicamentos-para-tratamento-de-doencas-raras-a-luz-da-nova-lei-de-licitacoes-e-contratos-administrativos","status":"publish","type":"post","link":"https:\/\/brzadvogados.com.br\/en\/aquisicoes-diretas-de-medicamentos-para-tratamento-de-doencas-raras-a-luz-da-nova-lei-de-licitacoes-e-contratos-administrativos\/","title":{"rendered":"(PT) Aquisi\u00e7\u00f5es diretas de medicamentos para tratamento de doen\u00e7as raras \u00e0 luz da  Nova Lei de Licita\u00e7\u00f5es e Contratos Administrativos"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/brzadvogados.com.br\/pb\/wp-json\/wp\/v2\/posts\/472\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pb\" title=\"PT\">PT<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in PT.<\/p>\n","protected":false},"author":1,"featured_media":473,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Doen\u00e7as Raras e SUS<\/title>\n<meta name=\"description\" content=\"Doen\u00e7as Raras e SUS\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/brzadvogados.com.br\/aquisicoes-diretas-de-medicamentos-para-tratamento-de-doencas-raras-a-luz-da-nova-lei-de-licitacoes-e-contratos-administrativos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Doen\u00e7as Raras e SUS\" \/>\n<meta property=\"og:description\" content=\"Doen\u00e7as Raras e SUS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/brzadvogados.com.br\/aquisicoes-diretas-de-medicamentos-para-tratamento-de-doencas-raras-a-luz-da-nova-lei-de-licitacoes-e-contratos-administrativos\/\" \/>\n<meta property=\"og:site_name\" content=\"BRZ Advogados\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-29T12:51:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-29T13:53:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2024\/07\/BRZ-post-site-10.png\" \/>\n\t<meta property=\"og:image:width\" content=\"753\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/brzadvogados.com.br\/aquisicoes-diretas-de-medicamentos-para-tratamento-de-doencas-raras-a-luz-da-nova-lei-de-licitacoes-e-contratos-administrativos\/\",\"url\":\"https:\/\/brzadvogados.com.br\/aquisicoes-diretas-de-medicamentos-para-tratamento-de-doencas-raras-a-luz-da-nova-lei-de-licitacoes-e-contratos-administrativos\/\",\"name\":\"Doen\u00e7as Raras e SUS\",\"isPartOf\":{\"@id\":\"https:\/\/brzadvogados.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/brzadvogados.com.br\/aquisicoes-diretas-de-medicamentos-para-tratamento-de-doencas-raras-a-luz-da-nova-lei-de-licitacoes-e-contratos-administrativos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/brzadvogados.com.br\/aquisicoes-diretas-de-medicamentos-para-tratamento-de-doencas-raras-a-luz-da-nova-lei-de-licitacoes-e-contratos-administrativos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2024\/07\/BRZ-post-site-10.png\",\"datePublished\":\"2024-02-29T12:51:52+00:00\",\"dateModified\":\"2024-07-29T13:53:53+00:00\",\"author\":{\"@id\":\"https:\/\/brzadvogados.com.br\/#\/schema\/person\/67b7ef290bb2c6524ff08a94bb1d355c\"},\"description\":\"Doen\u00e7as Raras e SUS\",\"breadcrumb\":{\"@id\":\"https:\/\/brzadvogados.com.br\/aquisicoes-diretas-de-medicamentos-para-tratamento-de-doencas-raras-a-luz-da-nova-lei-de-licitacoes-e-contratos-administrativos\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/brzadvogados.com.br\/aquisicoes-diretas-de-medicamentos-para-tratamento-de-doencas-raras-a-luz-da-nova-lei-de-licitacoes-e-contratos-administrativos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/brzadvogados.com.br\/aquisicoes-diretas-de-medicamentos-para-tratamento-de-doencas-raras-a-luz-da-nova-lei-de-licitacoes-e-contratos-administrativos\/#primaryimage\",\"url\":\"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2024\/07\/BRZ-post-site-10.png\",\"contentUrl\":\"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2024\/07\/BRZ-post-site-10.png\",\"width\":753,\"height\":627,\"caption\":\"Doen\u00e7as Raras e SUS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/brzadvogados.com.br\/aquisicoes-diretas-de-medicamentos-para-tratamento-de-doencas-raras-a-luz-da-nova-lei-de-licitacoes-e-contratos-administrativos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/brzadvogados.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aquisi\u00e7\u00f5es diretas de medicamentos para tratamento de doen\u00e7as raras \u00e0 luz da Nova Lei de Licita\u00e7\u00f5es e Contratos Administrativos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/brzadvogados.com.br\/#website\",\"url\":\"https:\/\/brzadvogados.com.br\/\",\"name\":\"BRZ Advogados\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/brzadvogados.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/brzadvogados.com.br\/#\/schema\/person\/67b7ef290bb2c6524ff08a94bb1d355c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/brzadvogados.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f17ad5b5be1eb9e6545c23206ddf516e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f17ad5b5be1eb9e6545c23206ddf516e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/brzadvogados.com.br\"],\"url\":\"https:\/\/brzadvogados.com.br\/en\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Doen\u00e7as Raras e SUS","description":"Doen\u00e7as Raras e SUS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/brzadvogados.com.br\/aquisicoes-diretas-de-medicamentos-para-tratamento-de-doencas-raras-a-luz-da-nova-lei-de-licitacoes-e-contratos-administrativos\/","og_locale":"en_US","og_type":"article","og_title":"Doen\u00e7as Raras e SUS","og_description":"Doen\u00e7as Raras e SUS","og_url":"https:\/\/brzadvogados.com.br\/aquisicoes-diretas-de-medicamentos-para-tratamento-de-doencas-raras-a-luz-da-nova-lei-de-licitacoes-e-contratos-administrativos\/","og_site_name":"BRZ Advogados","article_published_time":"2024-02-29T12:51:52+00:00","article_modified_time":"2024-07-29T13:53:53+00:00","og_image":[{"width":753,"height":627,"url":"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2024\/07\/BRZ-post-site-10.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/brzadvogados.com.br\/aquisicoes-diretas-de-medicamentos-para-tratamento-de-doencas-raras-a-luz-da-nova-lei-de-licitacoes-e-contratos-administrativos\/","url":"https:\/\/brzadvogados.com.br\/aquisicoes-diretas-de-medicamentos-para-tratamento-de-doencas-raras-a-luz-da-nova-lei-de-licitacoes-e-contratos-administrativos\/","name":"Doen\u00e7as Raras e SUS","isPartOf":{"@id":"https:\/\/brzadvogados.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/brzadvogados.com.br\/aquisicoes-diretas-de-medicamentos-para-tratamento-de-doencas-raras-a-luz-da-nova-lei-de-licitacoes-e-contratos-administrativos\/#primaryimage"},"image":{"@id":"https:\/\/brzadvogados.com.br\/aquisicoes-diretas-de-medicamentos-para-tratamento-de-doencas-raras-a-luz-da-nova-lei-de-licitacoes-e-contratos-administrativos\/#primaryimage"},"thumbnailUrl":"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2024\/07\/BRZ-post-site-10.png","datePublished":"2024-02-29T12:51:52+00:00","dateModified":"2024-07-29T13:53:53+00:00","author":{"@id":"https:\/\/brzadvogados.com.br\/#\/schema\/person\/67b7ef290bb2c6524ff08a94bb1d355c"},"description":"Doen\u00e7as Raras e SUS","breadcrumb":{"@id":"https:\/\/brzadvogados.com.br\/aquisicoes-diretas-de-medicamentos-para-tratamento-de-doencas-raras-a-luz-da-nova-lei-de-licitacoes-e-contratos-administrativos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/brzadvogados.com.br\/aquisicoes-diretas-de-medicamentos-para-tratamento-de-doencas-raras-a-luz-da-nova-lei-de-licitacoes-e-contratos-administrativos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/brzadvogados.com.br\/aquisicoes-diretas-de-medicamentos-para-tratamento-de-doencas-raras-a-luz-da-nova-lei-de-licitacoes-e-contratos-administrativos\/#primaryimage","url":"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2024\/07\/BRZ-post-site-10.png","contentUrl":"https:\/\/brzadvogados.com.br\/wp-content\/uploads\/2024\/07\/BRZ-post-site-10.png","width":753,"height":627,"caption":"Doen\u00e7as Raras e SUS"},{"@type":"BreadcrumbList","@id":"https:\/\/brzadvogados.com.br\/aquisicoes-diretas-de-medicamentos-para-tratamento-de-doencas-raras-a-luz-da-nova-lei-de-licitacoes-e-contratos-administrativos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/brzadvogados.com.br\/"},{"@type":"ListItem","position":2,"name":"Aquisi\u00e7\u00f5es diretas de medicamentos para tratamento de doen\u00e7as raras \u00e0 luz da Nova Lei de Licita\u00e7\u00f5es e Contratos Administrativos"}]},{"@type":"WebSite","@id":"https:\/\/brzadvogados.com.br\/#website","url":"https:\/\/brzadvogados.com.br\/","name":"BRZ Advogados","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/brzadvogados.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/brzadvogados.com.br\/#\/schema\/person\/67b7ef290bb2c6524ff08a94bb1d355c","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/brzadvogados.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f17ad5b5be1eb9e6545c23206ddf516e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f17ad5b5be1eb9e6545c23206ddf516e?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/brzadvogados.com.br"],"url":"https:\/\/brzadvogados.com.br\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/posts\/472"}],"collection":[{"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/comments?post=472"}],"version-history":[{"count":0,"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/posts\/472\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/media\/473"}],"wp:attachment":[{"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/media?parent=472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/categories?post=472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brzadvogados.com.br\/en\/wp-json\/wp\/v2\/tags?post=472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}